{"id":3333,"date":"2021-12-09T14:30:41","date_gmt":"2021-12-09T14:30:41","guid":{"rendered":"http:\/\/wordpress.thetruthtoledo.com\/wp-content\/uploads\/2021\/12\/use2.jpg"},"modified":"2021-12-09T14:30:41","modified_gmt":"2021-12-09T14:30:41","slug":"use2-6","status":"inherit","type":"attachment","link":"http:\/\/wordpress.thetruthtoledo.com\/index.php\/2021\/12\/09\/neighborworks-weatherization-program-brings-much-needed-relief-to-so-many-area-residents\/use2-6\/","title":{"rendered":"use2"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-3333","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/wordpress.thetruthtoledo.com\/wp-content\/uploads\/2021\/12\/use2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"261\" height=\"196\" src=\"http:\/\/wordpress.thetruthtoledo.com\/wp-content\/uploads\/2021\/12\/use2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":261,"height":196,"file":"2021\/12\/use2.jpg","sizes":{"thumbnail":{"file":"use2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/wordpress.thetruthtoledo.com\/wp-content\/uploads\/2021\/12\/use2-150x150.jpg"},"rpwe-thumbnail":{"file":"use2-45x45.jpg","width":45,"height":45,"mime_type":"image\/jpeg","source_url":"http:\/\/wordpress.thetruthtoledo.com\/wp-content\/uploads\/2021\/12\/use2-45x45.jpg"},"full":{"file":"use2.jpg","width":261,"height":196,"mime_type":"image\/jpeg","source_url":"http:\/\/wordpress.thetruthtoledo.com\/wp-content\/uploads\/2021\/12\/use2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":3327,"source_url":"http:\/\/wordpress.thetruthtoledo.com\/wp-content\/uploads\/2021\/12\/use2.jpg","_links":{"self":[{"href":"http:\/\/wordpress.thetruthtoledo.com\/index.php\/wp-json\/wp\/v2\/media\/3333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/wordpress.thetruthtoledo.com\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/wordpress.thetruthtoledo.com\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/wordpress.thetruthtoledo.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/wordpress.thetruthtoledo.com\/index.php\/wp-json\/wp\/v2\/comments?post=3333"}]}}